{"id":59958,"date":"2021-03-17T11:40:02","date_gmt":"2021-03-17T11:40:02","guid":{"rendered":"http:\/\/janus.bio\/?p=59958"},"modified":"2021-03-17T11:40:02","modified_gmt":"2021-03-17T11:40:02","slug":"ya-salio-el-boletin-sustentable-060","status":"publish","type":"post","link":"https:\/\/perfilvirtual.ar\/janus\/ya-salio-el-boletin-sustentable-060\/","title":{"rendered":"\u00a1Ya sali\u00f3 el Bolet\u00edn Sustentable N\u00b0060!"},"content":{"rendered":"<p>Presentamos la <strong>60\u00b0\u00a0edici\u00f3n<\/strong> del\u00a0<a href=\"http:\/\/janus.bio\/boletin-sustentable\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Bolet\u00edn Sustentable<\/strong><\/a>, un<strong>\u00a0formato<\/strong>\u00a0de comunicaci\u00f3n que enviamos\u00a0por\u00a0<strong>correo electr\u00f3nico <\/strong>y<strong>\u00a0Whatsapp<\/strong> a nuestras\u00a0<a href=\"http:\/\/janus.bio\/2019\/11\/05\/familias-asociadas-el-sosten-de-los-alimentos-vitales-y-nutritivos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Familias Asociadas: el sost\u00e9n de los alimentos vitales y nutritivos<\/strong><\/a>\u00a0y a todos los suscriptores de nuestra lista oficial, a trav\u00e9s del cual les hacemos llegar noticias de inter\u00e9s. Con esta iniciativa esperamos adem\u00e1s ampliar el\u00a0alcance a toda la comunidad\u00a0interesada.<\/p>\n<p>&nbsp;<\/p>\n<p>Los contenidos de cada env\u00edo peri\u00f3dico responden a necesidades puntuales de nuestra\u00a0<a href=\"http:\/\/janus.bio\/comunicacion-integrada\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Comunicaci\u00f3n Integrada<\/strong><\/a>, aquellas que como emprendimiento consideramos que\u00a0podr\u00edan resultar\u00a0un aporte\u00a0significativo a la transformaci\u00f3n de las condiciones de la realidad, que muchas veces aguardan nuestra acci\u00f3n individual articulada con otras en redes colectivas, basadas en sinton\u00eda de intereses. Los t\u00edtulos que vamos eligiendo para cada env\u00edo resumen de alg\u00fan modo el esp\u00edritu com\u00fan que integra los objetivos de cada una de las tres publicaciones que compartimos.<\/p>\n<p>&nbsp;<\/p>\n<h4>Janus Bolet\u00edn Sustentable N\u00b0 060 \/ Vitales y saludables continuidades<\/h4>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/bit.ly\/3trsi8M\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sesenta ediciones: el ritmo de la im permanencia cobija los prop\u00f3sitos<\/strong><\/a>,<\/li>\n<\/ul>\n<p style=\"padding-left: 60px;\">Gracias al enfoque integral, teor\u00edas, pr\u00e1cticas, acciones y reflexiones que utilizamos para desarrollar nuestro emprendimiento productivo sustentable y regenerativo, desde los inicios tuvimos claro que adem\u00e1s de la producci\u00f3n de alimentos saludables necesit\u00e1bamos aportar tambi\u00e9n el complemento comunicacional, de modo que nos permitiera ir conversando con la variedad de interlocutores cotidianos, a trav\u00e9s de varios canales que fuimos abriendo para mantenernos informados y atentos.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/bit.ly\/38PcdC5\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Compost en casa: Curso modalidad online por Zoom<\/strong><\/a>,<\/li>\n<\/ul>\n<p style=\"padding-left: 60px;\">Para quienes est\u00e9n interesados en capacitarse en la utilizaci\u00f3n de herramientas y conocimientos que les permitan vincularse m\u00e1s estrechamente a estas tem\u00e1ticas y producir sus propios alimentos en huertas familiares y urbanas, con las caracter\u00edsticas de Vitalidad y nutrici\u00f3n: dos pilares fundamentales de los alimentos saludables, presentamos una propuesta de capacitaci\u00f3n online basada en los fundamentos de la Agroecolog\u00eda y la Agricultura Biodin\u00e1mica.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"http:\/\/bit.ly\/2EDczf5\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Parador Janus: Dormi Grupal<\/strong><\/a>,<\/li>\n<\/ul>\n<p style=\"padding-left: 60px;\">Ubicado en la planta alta del \u00c1rea de Servicios y lindero con el Dormi Familiar, ofrecemos el Dormi Grupal totalmente equipado y confortable para recibir a viajeros, visitantes, practicantes y grupos que se acerquen al Parador Janus para disfrutar de la Experiencia Biodin\u00e1mica colectiva y el alojamiento compartido.<\/p>\n<p>&nbsp;<\/p>\n<p>Quienes\u00a0todav\u00eda no se hayan suscripto y deseen hacerlo, pueden\u00a0sumarse a nuestra<strong>\u00a0base de datos genuina<\/strong>\u00a0completando el\u00a0<a href=\"http:\/\/janus.bio\/contacto\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Formulario de Contacto<\/strong><\/a>\u00a0del sitio web. Con la continuidad de esta iniciativa esperamos seguir ampliando el\u00a0alcance\u00a0all\u00ed donde\u00a0siga habiendo inter\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-57909 size-thumbnail alignleft\" src=\"http:\/\/janus.bio\/wp-content\/uploads\/2020\/04\/LOGO-MAIL-WHATSAPP-150x150.png\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2020\/04\/LOGO-MAIL-WHATSAPP-150x150.png 150w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2020\/04\/LOGO-MAIL-WHATSAPP-300x300.png 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2020\/04\/LOGO-MAIL-WHATSAPP.png 316w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/strong>Una vez completado el formulario comenzar\u00e1n a recibir el\u00a0<strong>Bolet\u00edn Sustentable<\/strong>\u00a0por correo electr\u00f3nico y Whatsapp Empresas,\u00a0mientras dure esta etapa de aislamiento con una frecuencia quincenal. Luego de estar suscriptos, si no desean recibirlo por alguna de las dos v\u00edas, podr\u00e1n solicitar la baja a trav\u00e9s de los mecanismos que predeterminamos para cada cada formato.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Para quienes ya est\u00e1n suscriptos, recuerden que para\u00a0seguir recibiendo\u00a0los env\u00edos por Whatsapp Empresas deber\u00e1n tener agendado nuestro nuevo n\u00famero en sus contactos,\u00a0<\/em><a href=\"tel:+542995711049\"><strong>+549 299 5711049<\/strong><\/a><em>.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Conocer los factores de riesgo nos permitir\u00e1 elegir las opciones seguras:<\/strong><\/span>\u00a0todas nuestras actividades se realizan respetando con responsabilidad y compromiso el marco normativo\u00a0desarrollado por el Gobierno Nacional y explicado en nuestra p\u00e1gina web:\u00a0<a href=\"http:\/\/janus.bio\/2021\/02\/20\/alimentos-para-compartir-y-protocolos-para-cuidarnos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Alimentos para compartir y protocolos para cuidarnos<\/strong><\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Los invitamos a compartir, participar, comprometerse y disfrutar de nuestra\u00a0<a href=\"http:\/\/janus.bio\/experiencia-biodinamica\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Experiencia Biodin\u00e1mica<\/strong><\/a>\u00a0completando nuestro\u00a0<a href=\"http:\/\/janus.bio\/contacto\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Formulario de Contacto<\/strong><\/a>.\u00a0<em>\u00a1Gracias por elegir formar parte de la gran familia Janus!<\/em><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-59958 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-PORTADA-EDICION-060-1200-1024x538.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-PORTADA-EDICION-060-1200-1024x538.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-PORTADA-EDICION-060-1200-300x158.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-PORTADA-EDICION-060-1200-768x403.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-PORTADA-EDICION-060-1200-700x368.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-PORTADA-EDICION-060-1200.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-60-EDICIONES-OK-1024x538.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-60-EDICIONES-OK-1024x538.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-60-EDICIONES-OK-300x158.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-60-EDICIONES-OK-768x403.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-60-EDICIONES-OK-700x368.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/JANUS-BOLETIN-SUSTENTABLE-60-EDICIONES-OK.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-13-at-11.51-1024x538.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-13-at-11.51-1024x538.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-13-at-11.51-300x158.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-13-at-11.51-768x403.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-13-at-11.51-700x368.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-13-at-11.51.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"533\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/02\/DORMI-2-IMG_5079-1024x533.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/02\/DORMI-2-IMG_5079-1024x533.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/02\/DORMI-2-IMG_5079-300x156.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/02\/DORMI-2-IMG_5079-768x400.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/02\/DORMI-2-IMG_5079-700x365.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/02\/DORMI-2-IMG_5079.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 478px; top: 1776.44px;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Presentamos la 60\u00b0\u00a0edici\u00f3n del\u00a0Bolet\u00edn Sustentable, un\u00a0formato\u00a0de comunicaci\u00f3n que enviamos\u00a0por\u00a0correo electr\u00f3nico y\u00a0Whatsapp a nuestras\u00a0Familias Asociadas: el sost\u00e9n de los alimentos vitales y nutritivos\u00a0y a todos los suscriptores de nuestra lista oficial, a trav\u00e9s del cual les hacemos llegar noticias de inter\u00e9s. Con esta iniciativa esperamos adem\u00e1s ampliar el\u00a0alcance a toda la comunidad\u00a0interesada. &nbsp; Los contenidos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"footnotes":""},"categories":[202],"tags":[206],"class_list":["post-59958","post","type-post","status-publish","format-gallery","hentry","category-comunicacion-integrada","tag-boletin-sustentable","post_format-post-format-gallery"],"acf":[],"_links":{"self":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts\/59958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/comments?post=59958"}],"version-history":[{"count":1,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts\/59958\/revisions"}],"predecessor-version":[{"id":59961,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts\/59958\/revisions\/59961"}],"wp:attachment":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/media?parent=59958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/categories?post=59958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/tags?post=59958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}