{"id":54366,"date":"2019-04-24T13:41:11","date_gmt":"2019-04-24T13:41:11","guid":{"rendered":"http:\/\/janus.bio\/?p=54366"},"modified":"2019-08-01T14:22:49","modified_gmt":"2019-08-01T14:22:49","slug":"remo-venica-e-irmina-kleiner-de-naturaleza-viva-pioneros-y-protagonistas-del-cambio-de-paradigma","status":"publish","type":"post","link":"https:\/\/perfilvirtual.ar\/janus\/remo-venica-e-irmina-kleiner-de-naturaleza-viva-pioneros-y-protagonistas-del-cambio-de-paradigma\/","title":{"rendered":"Pioneros y protagonistas del cambio de paradigma"},"content":{"rendered":"<p>Compartimos\u00a0<a href=\"http:\/\/www.lavanguardiadigital.com.ar\/index.php\/2019\/03\/13\/remo-venica-e-irmina-kleiner-se-puede-producir-sin-agredir-al-suelo-sin-envenenar-los-alimentos-y-siendo-protagonistas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>una noticia recientemente publicada en La Vanguardia Digital<\/strong><\/a>\u00a0\u2014a ra\u00edz de la participaci\u00f3n de los protagonistas en el <a href=\"http:\/\/www.gualeguaychu.gov.ar\/passs\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Congreso PASSS<\/strong><\/a> realizado en Gualeguaych\u00fa, Entre R\u00edos\u2014 en la que los agricultores <strong>Remo V\u00e9nica<\/strong> e <strong>Irmina Kleiner<\/strong> dialogan con el periodista <strong>Am\u00e9rico Schvartzman<\/strong> acerca de los or\u00edgenes, el presente y el devenir de <a href=\"http:\/\/granjanaturalezaviva.com.ar\/site\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Naturaleza Viva<\/strong><\/a>, uno de los proyectos agr\u00edcolas m\u00e1s significativos de los \u00faltimos a\u00f1os, modelo insoslayable de producci\u00f3n sustentable\u00a0para la Argentina y el mundo,\u00a0basado en la <a href=\"http:\/\/janus.bio\/agricultura-biodinamica\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Agricultura Biodin\u00e1mica<\/strong><\/a> y la <strong>Agroecolog\u00eda<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>M\u00e1s all\u00e1 de las diferencias de trayectoria y escala, podr\u00edamos decir que la visi\u00f3n y el modelo que implementamos en <strong>Janus Proyecto Rural Integrador<\/strong> abrevan en las mismas fuentes que los de <strong>Naturaleza Viva<\/strong>: por un lado, <strong>familias de agricultores<\/strong> trabajando la tierra\u00a0utilizando\u00a0diferentes modalidades de producci\u00f3n sustentable, con enfoque hol\u00edstico\u00a0y sin uso de agroqu\u00edmicos, produciendo alimentos vitales y nutritivos abarcando toda la cadena de agregado de valor, desde la semilla al producto elaborado. Por otro lado\u00a0\u2014en conexi\u00f3n directa y pr\u00e1cticamente sin intermediarios\u2014 individuos, familias y grupos de<strong> consumidores responsables<\/strong> cada d\u00eda m\u00e1s empoderados tomando las riendas de su salud y alimentaci\u00f3n, basando la toma de decisiones de sus compras en una activa participaci\u00f3n social, incorporando nuevos conocimientos y pr\u00e1cticas, conscientes de la importancia del rol que ocupan\u00a0en la b\u00fasqueda del equilibrio de los sistemas de intercambio.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><em>Los responsables de \u201cNaturaleza Viva\u201d explican aqu\u00ed c\u00f3mo es posible producir sin agredir a la naturaleza, sin envenenar los alimentos y sin esclavizarse como productores. La calma de Irina contrasta con Remo, quien habla con un apasionamiento admirable. Por supuesto, la transcripci\u00f3n de la entrevista no logra transmitir la calidez y entusiasmo de sus voces, al contar c\u00f3mo fue apostar \u2013treinta a\u00f1os atr\u00e1s\u2013 a lo que aun no se conoc\u00eda con el nombre de agroecolog\u00eda: el modo m\u00e1s natural de emanciparse de las deudas que los agobiaban. Y aseguran que esta forma de producir vuelve a poner en el centro, junto a la naturaleza, \u201cal productor, le devuelve las ganas de vivir, el entusiasmo, porque pasa a ser la parte m\u00e1s importante del proceso productivo\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><em>\u201cLa fertilidad se mantiene a trav\u00e9s del ciclado de los elementos de nuestro ecosistema: el sol es gratis, el aire es gratis, el agua es gratis y la tierra es naturalmente gratis para el campesino. Un correcto manejo del sol, del aire, de la tierra y del agua optimiza la producci\u00f3n\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><em>\u201cEstamos acostumbrados a ver los campos libres de personas, de individuos, de familias. Tenemos que replantearnos seriamente esto, es muy grave lo que ha sucedido. Tenemos que repoblar la tierra\u201d.<\/em><\/p>\n<p>&nbsp;<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/wKZZkxnybrc\" width=\"720\" height=\"405\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n&nbsp;<br \/>\nLos invitamos a compartir, participar, comprometerse y disfrutar de nuestra\u00a0<a href=\"http:\/\/janus.bio\/experiencia-biodinamica\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Experiencia Biodin\u00e1mica<\/strong><\/a>\u00a0completando nuestro\u00a0<a href=\"http:\/\/janus.bio\/contacto\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Formulario de Contacto<\/strong><\/a>.\u00a0<em>\u00a1Gracias por elegir formar parte de la gran familia Janus!<\/em><br \/>\n&nbsp;<br \/>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-54366 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"533\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/grupo-humano-naturaleza-viva-1024x533.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/grupo-humano-naturaleza-viva-1024x533.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/grupo-humano-naturaleza-viva-300x156.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/grupo-humano-naturaleza-viva-768x400.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/grupo-humano-naturaleza-viva-700x365.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/grupo-humano-naturaleza-viva.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"533\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/Remo-Venica-e-Irmina-Kleiner-Se-puede-producir-sin-agredir-al-suelo-sin-envenenar-los-alimentos-y-siendo-protagonistas-1024x533.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/Remo-Venica-e-Irmina-Kleiner-Se-puede-producir-sin-agredir-al-suelo-sin-envenenar-los-alimentos-y-siendo-protagonistas-1024x533.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/Remo-Venica-e-Irmina-Kleiner-Se-puede-producir-sin-agredir-al-suelo-sin-envenenar-los-alimentos-y-siendo-protagonistas-300x156.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/Remo-Venica-e-Irmina-Kleiner-Se-puede-producir-sin-agredir-al-suelo-sin-envenenar-los-alimentos-y-siendo-protagonistas-768x400.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/Remo-Venica-e-Irmina-Kleiner-Se-puede-producir-sin-agredir-al-suelo-sin-envenenar-los-alimentos-y-siendo-protagonistas-700x365.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/Remo-Venica-e-Irmina-Kleiner-Se-puede-producir-sin-agredir-al-suelo-sin-envenenar-los-alimentos-y-siendo-protagonistas.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"533\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/remo-cosechando-mandarinas-1024x533.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/remo-cosechando-mandarinas-1024x533.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/remo-cosechando-mandarinas-300x156.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/remo-cosechando-mandarinas-768x400.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/remo-cosechando-mandarinas-700x365.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/remo-cosechando-mandarinas.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"533\" src=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/biodigestor-naturaleza-viva-1024x533.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/biodigestor-naturaleza-viva-1024x533.jpg 1024w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/biodigestor-naturaleza-viva-300x156.jpg 300w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/biodigestor-naturaleza-viva-768x400.jpg 768w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/biodigestor-naturaleza-viva-700x365.jpg 700w, https:\/\/perfilvirtual.ar\/janus\/wp-content\/uploads\/2019\/04\/biodigestor-naturaleza-viva.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compartimos\u00a0una noticia recientemente publicada en La Vanguardia Digital\u00a0\u2014a ra\u00edz de la participaci\u00f3n de los protagonistas en el Congreso PASSS realizado en Gualeguaych\u00fa, Entre R\u00edos\u2014 en la que los agricultores Remo V\u00e9nica e Irmina Kleiner dialogan con el periodista Am\u00e9rico Schvartzman acerca de los or\u00edgenes, el presente y el devenir de Naturaleza Viva, uno de los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"footnotes":""},"categories":[137,216,202],"tags":[],"class_list":["post-54366","post","type-post","status-publish","format-gallery","hentry","category-agricultura-biodinamica","category-alimentos-vitales-y-nutritivos","category-comunicacion-integrada","post_format-post-format-gallery"],"acf":[],"_links":{"self":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts\/54366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/comments?post=54366"}],"version-history":[{"count":21,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts\/54366\/revisions"}],"predecessor-version":[{"id":54485,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/posts\/54366\/revisions\/54485"}],"wp:attachment":[{"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/media?parent=54366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/categories?post=54366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perfilvirtual.ar\/janus\/wp-json\/wp\/v2\/tags?post=54366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}